{"id":85095,"date":"2026-07-12T04:00:06","date_gmt":"2026-07-12T08:00:06","guid":{"rendered":"https:\/\/veneportal.com\/noticias\/2026\/07\/12\/ucrania-rechaza-reincorporacion-de-rusia-en-los-juegos-olimpicos-2\/"},"modified":"2026-07-12T04:00:06","modified_gmt":"2026-07-12T08:00:06","slug":"ucrania-rechaza-reincorporacion-de-rusia-en-los-juegos-olimpicos-2","status":"publish","type":"post","link":"https:\/\/veneportal.com\/noticias\/2026\/07\/12\/ucrania-rechaza-reincorporacion-de-rusia-en-los-juegos-olimpicos-2\/","title":{"rendered":"Ucrania rechaza reincorporaci\u00f3n de Rusia en los Juegos Ol\u00edmpicos"},"content":{"rendered":"<p>El Comit\u00e9 Ol\u00edmpico Internacional (COI) decidi\u00f3 suavizar a\u00fan m\u00e1s las sanciones contra los deportistas rusos. El ministro de Deportes de Ucrania, Matwij Bidnyj, formula acusaciones contra el COI y su presidenta.Aproximadamente cuatro a\u00f1os y medio despu\u00e9s de la invasi\u00f3n de Ucrania y a pesar de los continuos combates, el Comit\u00e9 Ol\u00edmpico Internacional (COI) ha permitido que los deportistas rusos vuelvan a participar en las pruebas de clasificaci\u00f3n para los Juegos Ol\u00edmpicos de Los \u00c1ngeles 2028, incluso en deportes de equipo, tal y como explic\u00f3 la presidenta de la entidad, Kirsty Coventry. Con ello, es probable que la delegaci\u00f3n ol\u00edmpica rusa en Los \u00c1ngeles aumente considerablemente. En Par\u00eds 2024 solo participaron 15 &#8220;deportistas neutrales&#8221;, y en los Juegos Ol\u00edmpicos de Invierno de Mil\u00e1n y Cortina, apenas 13. Es cierto que, al menos por el momento, los rusos siguen sin poder competir bajo la bandera rusa, y el himno nacional tampoco se tocar\u00e1 en las competiciones hasta nuevo aviso. Sin embargo, se ha indicado que &#8220;a su debido tiempo&#8221; se decidir\u00e1 sobre el uso de s\u00edmbolos rusos en los Juegos Ol\u00edmpicos. Invitaci\u00f3n a la presidenta del COI &#8220;Me gustar\u00eda invitar a Kirsty Coventry a Ucrania para que vea la realidad con sus propios ojos&#8221;, declar\u00f3 el ministro de Deportes ucraniano, Matwij Bidnyj, en una declaraci\u00f3n enviada a Deutsche Welle. &#8220;Me gustar\u00eda que estuviera en nuestros andenes y viera c\u00f3mo nuestros soldados se despiden de sus hijos antes de partir al frente. Me gustar\u00eda que visitara nuestras academias deportivas destruidas y conociera a nuestros j\u00f3venes atletas, que tienen que entrenar bajo el ulular de las sirenas antia\u00e9reas&#8221;, afirm\u00f3 Bidnyj, que est\u00e1 absolutamente convencido de que cualquier discurso sobre la &#8220;neutralidad&#8221; o el &#8220;cumplimiento de las normas de procedimiento&#8221; se acallar\u00eda de inmediato en cuanto ella viviera de primera mano lo que ocurre en Ucrania. Tambi\u00e9n el piloto de skeleton Vladislav Heraskewytsch, al que no se le permiti\u00f3 competir en los Juegos de Invierno de Cortina debido a que su casco ten\u00eda pintadas im\u00e1genes de deportistas ucranianos fallecidos, habl\u00f3 de &#8220;hipocres\u00eda&#8221; y afirm\u00f3 que el COI &#8220;permite a los terroristas volver al deporte de alta competencia&#8221;. La exclusi\u00f3n de los Juegos Ol\u00edmpicos no se debi\u00f3 a la guerra Sin embargo, la guerra de agresi\u00f3n de Rusia nunca fue para el COI la raz\u00f3n principal para excluir a los deportistas rusos de los Juegos Ol\u00edmpicos, al menos no desde un punto de vista puramente jur\u00eddico. M\u00e1s bien, el organismo rector sancion\u00f3 el hecho de que Rusia hubiera integrado en el sistema federativo ruso a las federaciones deportivas ucranianas de las regiones anexionadas y ocupadas de Donetsk, Lugansk, Jers\u00f3n y Zaporiyia. Desde el punto de vista del COI, esto constitu\u00eda una violaci\u00f3n de la Carta Ol\u00edmpica. Y dado que Rusia retir\u00f3 formalmente a estas federaciones, el COI ya no tiene fundamento jur\u00eddico para seguir excluyendo al Comit\u00e9 Ol\u00edmpico Ruso (ROC). Sin embargo, resulta un tanto incoherente que Bielorrusia, como pa\u00eds que apoyaba a Rusia, tambi\u00e9n estuviera excluida durante tanto tiempo, toda vez que los bielorrusos nunca integraron por la fuerza a ninguna federaci\u00f3n deportiva en sus propias estructuras ni ocuparon territorios ucranianos. Para el COI bast\u00f3 con que Bielorrusia hubiera apoyado activamente, tanto log\u00edstica como militarmente, la guerra de agresi\u00f3n de los rusos y hubiera permitido a las tropas rusas lanzaran ataques desde territorio bielorruso. El COI consider\u00f3 que esto supon\u00eda una violaci\u00f3n de la paz ol\u00edmpica. No obstante, las sanciones se levantaron por completo en mayo de 2026. La justificaci\u00f3n en aquel momento fue el cumplimiento de todas las normas por parte del Comit\u00e9 Ol\u00edmpico Bielorruso, as\u00ed como el comportamiento ejemplar de sus deportistas. &#8220;Quer\u00edamos garantizar a todos los deportistas la posibilidad de participar en los Juegos Ol\u00edmpicos sin que se les responsabilizara de las acciones de su Gobierno&#8221;, se justific\u00f3 Coventry. Ucrania habla de una &#8220;artima\u00f1a jur\u00eddica&#8221; de Rusia Ucrania no comprende las nuevas determinaciones del COI. &#8220;Esta decisi\u00f3n supone un desprecio absoluto hacia la memoria de cientos de deportistas ucranianos asesinados por Rusia&#8221;, escribe el ministro Bidnyj a DW. Adem\u00e1s, el COI habr\u00eda ca\u00eddo en una artima\u00f1a jur\u00eddica de los rusos. Dado que el Comit\u00e9 Ol\u00edmpico Ruso (ROC) elimin\u00f3 en diciembre de 2024 todos los consejos regionales de sus estatutos, Donetsk, Lugansk, Jers\u00f3n y Zaporiyia ya no figuraban en ellos. \u00bfAtletismo no, f\u00fatbol s\u00ed? La rapidez y el alcance con que se produzca realmente el regreso de los deportistas rusos depender\u00e1 de cada federaci\u00f3n deportiva. Dado que el COI ha revocado su antigua recomendaci\u00f3n de excluir a Rusia, estas pueden decidir a su discreci\u00f3n. Y est\u00e1n reaccionando de forma diferente. Mientras que la Federaci\u00f3n Internacional de Atletismo (World Athletics) acaba de prorrogar de nuevo la exclusi\u00f3n de Rusia, otras federaciones internacionales, como las de nataci\u00f3n, gimnasia o judo, ya han levantado todas las sanciones. Se considera probable que otros deportes sigan su ejemplo. El presidente de la FIFA, Gianni Infantino, tambi\u00e9n se muestra desde hace meses abierto a un regreso de Rusia. A mediados de junio, Rusia ya fue admitida para el Mundial Sub-15 que se celebrar\u00e1 en octubre en Azerbaiy\u00e1n. Seg\u00fan la cadena brit\u00e1nica Sky News, la Federaci\u00f3n Internacional de F\u00fatbol est\u00e1 barajando la posibilidad de readmitir a Rusia en su totalidad. Las reacciones en el Kremlin fueron positivas: &#8220;El COI env\u00eda una se\u00f1al clara: el movimiento ol\u00edmpico debe permanecer al margen de la pol\u00edtica&#8221;, elogi\u00f3 el ministro de Deportes ruso, Mijail Degtjarjov, a trav\u00e9s de Telegram. (mn\/dz)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Comit\u00e9 Ol\u00edmpico Internacional (COI) decidi\u00f3 suavizar a\u00fan m\u00e1s las sanciones contra los deportistas rusos. El ministro de Deportes de Ucrania, Matwij Bidnyj, formula acusaciones contra el COI y su&hellip; <\/p>\n","protected":false},"author":505,"featured_media":85094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-85095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts\/85095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/users\/505"}],"replies":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/comments?post=85095"}],"version-history":[{"count":0,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts\/85095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/media\/85094"}],"wp:attachment":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/media?parent=85095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/categories?post=85095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/tags?post=85095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}