{"id":54176,"date":"2023-12-31T12:04:11","date_gmt":"2023-12-31T17:04:11","guid":{"rendered":"https:\/\/veneportal.com\/noticias\/2023\/12\/31\/prosiguen-los-ataques-en-gaza-en-visperas-de-ano-nuevo\/"},"modified":"2023-12-31T12:04:11","modified_gmt":"2023-12-31T17:04:11","slug":"prosiguen-los-ataques-en-gaza-en-visperas-de-ano-nuevo","status":"publish","type":"post","link":"https:\/\/veneportal.com\/noticias\/2023\/12\/31\/prosiguen-los-ataques-en-gaza-en-visperas-de-ano-nuevo\/","title":{"rendered":"Prosiguen los ataques en Gaza en v\u00edsperas de A\u00f1o Nuevo"},"content":{"rendered":"<p>Siga aqu\u00ed minuto a minuto las noticias sobre los m\u00e1s recientes enfrentamientos en el Cercano Oriente provocados por los ataques del grupo terrorista Ham\u00e1s contra Israel el 7 de octubre de 2023.<br \/>\n\tHam\u00e1s reporta un nuevo balance de 21.822 muertos en Gaza.<br \/>\n\tNetanyahu afirma que la guerra de Israel en Gaza es de &#8220;una moralidad sin parang\u00f3n&#8221;.<br \/>\n\tLa naviera Maersk pausa la navegaci\u00f3n ante ataques hut\u00edes en el mar Rojo.<br \/>\n\tLa guerra entre Israel y Ham\u00e1s no cesa en v\u00edsperas de a\u00f1o nuevo<\/p>\n<p>Israel nombra nuevo ministro de Asuntos Exteriores<br \/>\nEl pol\u00edtico Israel Katz, actual ministro de Energ\u00eda de Israel, ser\u00e1 el nuevo encargado de Asuntos Exteriores en sustituci\u00f3n de Eli Cohen, anunci\u00f3 el Gobierno del primer ministro Benjam\u00edn Netanyahu este domingo (31.12.2023).<\/p>\n<p>Con este cambio, que llega un a\u00f1o despu\u00e9s de la formaci\u00f3n del actual Ejecutivo y que se enmarca en la rotaci\u00f3n ministerial que est\u00e1 sujeta a la aprobaci\u00f3n parlamentaria, Cohen pasar\u00e1 a ocupar el puesto que deja Katz en la cartera de Energ\u00eda, aunque seguir\u00e1 en el Gabinete de Seguridad de Israel, seg\u00fan un comunicado del Gobierno.<\/p>\n<p>&#8220;El Gobierno ha aprobado el nombramiento de Eli Cohen como ministro de Energ\u00eda e Infraestructuras&#8230; y el de Israel Katz como ministro de Asuntos Exteriores&#8221;, dice el comunicado, recogido por varias agencias. (efe, reuters, dpa \/ aa)<\/p>\n<p>Netanyahu afirma que la guerra de Israel en Gaza es de &#8220;una moralidad sin parang\u00f3n&#8221;<br \/>\nEl primer ministro israel\u00ed, Benjamin Netanyahu, afirm\u00f3 este domingo (31.12.2023) que la guerra que libra el ej\u00e9rcito israel\u00ed en la Franja de Gaza es de &#8220;una moralidad sin parang\u00f3n&#8221;, despu\u00e9s de que Sud\u00e1frica acusara al pa\u00eds de &#8220;actos de genocidio&#8221; ante la Corte Internacional de Justicia (CIJ).<\/p>\n<p>&#8220;Continuaremos nuestra guerra defensiva, cuya justicia y moralidad no tienen parang\u00f3n&#8221;, declar\u00f3 Netanyahu al inicio de una reuni\u00f3n de su gobierno.<\/p>\n<p>El Ej\u00e9rcito de Israel act\u00faa &#8220;lo m\u00e1s moralmente posible, haciendo todo para evitar da\u00f1ar a civiles, mientras Ham\u00e1s (&#8230;) los usa como escudos humanos&#8221;, a\u00f1adi\u00f3. (efe, afp \/ aa) <\/p>\n<p>Maersk pausa la navegaci\u00f3n ante ataques hut\u00edes en el mar Rojo<br \/>\nEl gigante holand\u00e9s del transporte mar\u00edtimo Maersk suspende durante 48 horas la navegaci\u00f3n a trav\u00e9s del Mar Rojo, despu\u00e9s de que uno de sus cargueros fuera atacado dos veces en 24 horas por los rebeldes hut\u00edes de Yemen -apoyados por Ir\u00e1n- anunci\u00f3 la empresa este domingo (31.12.2023), que ahora trata de investigar el incidente y evaluar la situaci\u00f3n de seguridad. <\/p>\n<p>El ataque fue el \u00faltimo de los perpetrados por militantes hut\u00edes en Yemen, que han atacado buques en el Mar Rojo para mostrar su apoyo a la organizaci\u00f3n terrorista Ham\u00e1s.<\/p>\n<p>El Comando Central Naval de Estados Unidos (CENTCOM) anunci\u00f3 previamente que hab\u00eda respondido a un ataque con fuego de los rebeldes chi\u00edes hut\u00edes en el mar Rojo y hundido tres barcas de los atacantes, lo que marca las primeras v\u00edctimas del movimiento yemen\u00ed en una confrontaci\u00f3n directa con las fuerzas estadounidenses en esta v\u00eda mar\u00edtima. (afp, reuters, dpa \/ aa)<\/p>\n<p>Ham\u00e1s reporta nuevo balance de 21.822 muertos en Gaza desde el comienzo de la ofensiva israel\u00ed<br \/>\nUn total de 21.822 personas han muerto y 56.451 han resultado heridas en ataques israel\u00edes en Gaza desde el 7 de octubre, seg\u00fan inform\u00f3 este domingo (31.12.2023) el Ministerio de Salud de la Franja, administrado por el grupo terrorista Ham\u00e1s.<\/p>\n<p>La cifra incluye 150 muertes y 286 heridos en las \u00faltimas 24 horas, seg\u00fan un comunicado del ministerio, que a\u00f1adi\u00f3 que 56.451 personas han resultado heridas en Gaza tras 86 d\u00edas desde que estallara el conflicto. (reuters, afp \/ aa)<\/p>\n<p>Israel prosigue sus ataques contra Gaza en el norte y el sur<br \/>\nEl conflicto entre Israel y el grupo terrorista Ham\u00e1salcanza su jornada 86 en el \u00faltimo d\u00eda de 2023, mientras la crisis humanitaria se agrava cada vez m\u00e1s en la Franja de Gaza, donde ya suman m\u00e1s de 21.000 muertos.<\/p>\n<p>Las tropas israel\u00edes continuaban este domingo (31.12.2023) su ofensiva por aire, tierra y mar sobre todo el largo del enclave palestino: en el norte, afianzaban su control, mientras en el sur, donde se cree que se esconde Yahya Sinwar, el l\u00edder de Ham\u00e1s en la Franja, incrementaban los ataques.<\/p>\n<p>En Beit Lahia, en el norte del enclave, las fuerzas israel\u00edes &#8220;identificaron a tres terroristas&#8221; que ingresaban a un edificio, que fue bombardeado, a\u00f1adieron. Cerca de ah\u00ed, en el campo de refugiados Shati, las tropas israel\u00edes &#8220;encontraron un jard\u00edn de infancia donde hab\u00eda infraestructura terrorista, incluidos artefactos explosivos&#8221; que fueron neutralizados, explic\u00f3 la fuente seg\u00fan pudo recoger la agencia Efe.<\/p>\n<p>En el sur del enclave, los soldados descubrieron dos bocas de t\u00faneles y en la ciudad de Jan Yunis, el ej\u00e9rcito israel\u00ed tambi\u00e9n habr\u00eda asaltado el cuartel general de Ham\u00e1s, que se encontraba ah\u00ed junto a otros servicios de inteligencia del grupo terrorista, seg\u00fan pudo comentar un funcionario israel\u00ed este s\u00e1bado por la noche. (dpa, efe \/ aa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siga aqu\u00ed minuto a minuto las noticias sobre los m\u00e1s recientes enfrentamientos en el Cercano Oriente provocados por los ataques del grupo terrorista Ham\u00e1s contra Israel el 7 de octubre&hellip; <\/p>\n","protected":false},"author":505,"featured_media":54177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-54176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts\/54176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/users\/505"}],"replies":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/comments?post=54176"}],"version-history":[{"count":0,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts\/54176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/media\/54177"}],"wp:attachment":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/media?parent=54176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/categories?post=54176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/tags?post=54176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}