{"id":35153,"date":"2022-11-28T23:00:03","date_gmt":"2022-11-29T04:00:03","guid":{"rendered":"https:\/\/veneportal.com\/noticias\/2022\/11\/28\/sergio-moro-la-candidatura-de-bolsonaro-era-la-mejor-opcion-2\/"},"modified":"2022-11-28T23:00:03","modified_gmt":"2022-11-29T04:00:03","slug":"sergio-moro-la-candidatura-de-bolsonaro-era-la-mejor-opcion-2","status":"publish","type":"post","link":"https:\/\/veneportal.com\/noticias\/2022\/11\/28\/sergio-moro-la-candidatura-de-bolsonaro-era-la-mejor-opcion-2\/","title":{"rendered":"Sergio Moro: &#8220;La candidatura de Bolsonaro era la mejor opci\u00f3n&#8221;"},"content":{"rendered":"<p>El exjuez brasile\u00f1o Sergio Moro habla con DW sobre su reaproximaci\u00f3n al bolsonarismo y dice que las protestas deben servir de alerta para el pr\u00f3ximo Gobierno de Lula.Exjuez federal, exministro, exconsultor y exprecandidado presidencial, Sergio Moro estrenar\u00e1 en 2023 una nueva funci\u00f3n: la de senador por el estado de Paran\u00e1. Como juez, Moro lider\u00f3 la investigaci\u00f3n en la operaci\u00f3n Lava Jato, pero parte de sus decisiones fueron luego anuladas por el Supremo Tribunal Federal (STF), incluyendo la condena de Luiz In\u00e1cio Lula da Silva.<\/p>\n<p>Moro se hab\u00eda distanciado tambi\u00e9n de Jair Bolsonaro, del que fue ministro, pero luego de no prosperar su propia precandidatura presidencial y ganar un esca\u00f1o senatorial, lo asesor\u00f3 en la campa\u00f1a para la segunda vuelta electoral, en la que fue derrotado por Lula.<\/p>\n<p>DW: En enero, cuando a\u00fan aspiraba a disputar la presidencia, Ud. dijo que &#8220;elegir a Lula o a Bolsonaro&#8221; ser\u00eda un &#8220;suicidio&#8221;. Meses despu\u00e9s, asesor\u00f3 a Bolsonaro en debates. \u00bfPor qu\u00e9 volvi\u00f3 a aproximarse al presidente?<\/p>\n<p>Sergio Moro: Desde el principio, me posicion\u00e9 como defensor de la tercera v\u00eda y present\u00e9 una precandidatura presidencial, porque pienso que la polarizaci\u00f3n es negativa para el pa\u00eds y lleva a radicalismos. Se necesita una posici\u00f3n moderada, de centro. Pero no fue viable, no solo mi candidatura, sino tampoco otras de tercera v\u00eda. Entonces, en la segunda vuelta, tuvimos dos opciones: Bolsonaro y Lula. (\u2026) Teniendo que escoger, me puse del lado del presidente Bolsonaro. No he cambiado mi opini\u00f3n sobre el pasado, mantengo las razones de mi ruptura con el Gobierno. Pero, dentro de las opciones disponibles, pens\u00e9 que la candidatura de Bolsonaro era la mejor.<\/p>\n<p>\u00bfC\u00f3mo actuar\u00e1 con Lula como presidente? <\/p>\n<p>Ser\u00e9 oposici\u00f3n. Claro que no ser\u00e1 una oposici\u00f3n irracional. No rechazaremos lo que nos parezca bueno para el pa\u00eds solo por venir de un Gobierno al que nos oponemos.<\/p>\n<p>Ahora, est\u00e1 claro que no veo que vendr\u00e1n propuestas de ese Gobierno en el \u00e1rea anticorrupci\u00f3n. As\u00ed que tengo la intenci\u00f3n de ser un senador vigilante. Un poco en la l\u00ednea de guardi\u00e1n de la Rep\u00fablica, como tiene que ser el Senado.<\/p>\n<p>\u00bfQu\u00e9 piensa de las protestas de bolsonaristas que no reconocen el resultado electoral?<\/p>\n<p>Creo que estas protestas revelan un gran descontento con los resultados electorales y una oposici\u00f3n a la propuesta del PT (Partido de los Trabajadores) para el pa\u00eds. Quien gan\u00f3, al final, no fue tanto el PT, sino este rechazo al Gobierno de Bolsonaro, que hizo algunas cosas buenas tambi\u00e9n, hay que destacarlo. La econom\u00eda no estaba exactamente en una mala situaci\u00f3n, el desempleo estaba bajando, pero hubo una serie de fallos que acabaron comprometiendo la reelecci\u00f3n.<\/p>\n<p>Esas manifestaciones, mientras sean pac\u00edficas \u2014aunque no concuerdo con algunas cosas, como los bloqueos\u2014 revelan esa insatisfacci\u00f3n. Es parte de la democracia que las personas puedan protestar. Las manifestaciones deber\u00edan ser interpretadas de forma apropiada, en el sentido de alertar al nuevo Gobierno de que requerir\u00e1 cautela, prudencia, y tendr\u00e1 que buscar posiciones moderadas, ya que existe una gran oposici\u00f3n e insatisfacci\u00f3n popular en relaci\u00f3n con el resultado de las elecciones.<\/p>\n<p>En 2018, el rumbo de la elecci\u00f3n presidencial se vio alterado por la condena a prisi\u00f3n que en ese entonces afectaba a Lula, que no se pudo presentar como candidato\u2026<\/p>\n<p>Fue una consecuencia indeseada porque, al final, el Poder Judicial aplica la ley. Yo apliqu\u00e9 la ley en esos casos, la condena del expresidente fue emitida no solo por m\u00ed, sino por otros jueces. Fue confirmada en el tribunal de apelaci\u00f3n de Porto Alegre, fue confirmada en Brasilia, el propio Supremo Tribunal Federal autoriz\u00f3 en su momento la detenci\u00f3n del expresidente. As\u00ed que fue una consecuencia, en el fondo no deseada, pero una consecuencia derivada no de la aplicaci\u00f3n de la ley, sino de la comisi\u00f3n de los delitos descubiertos en la operaci\u00f3n Lava Jato.<\/p>\n<p>En marzo de 2021, el STF anul\u00f3 las condenas de Lula, por entender que los casos estaban fuera de la jurisdicci\u00f3n correcta. Entonces, el tribunal entendi\u00f3 que usted era parcial, comprometiendo el derecho de la defensa a un juicio justo. \u00bfCu\u00e1l es su opini\u00f3n sobre la decisi\u00f3n del STF?<\/p>\n<p>Para m\u00ed, fue un error judicial anular las condenas, pero es momento de mirar hacia adelante. Miremos hacia adelante y veamos c\u00f3mo podemos construir despu\u00e9s de esto, establecer las condiciones necesarias para que tengamos una prevenci\u00f3n y represi\u00f3n cualificada de la corrupci\u00f3n en Brasil, que es una meta para cualquier pa\u00eds. No hay democracia moderna que se sostenga con la corrupci\u00f3n, no hay econom\u00eda que sea eficiente si se tiene el despilfarro inherente al soborno generalizado.<\/p>\n<p>Pero ahora hemos tenido unas elecciones y tenemos que mirar hacia adelante, no tiene sentido quedarse en el pasado. Tengo la conciencia tranquila por lo que hice y mi decisi\u00f3n en su momento fue confirmada por otros jueces de otros tribunales, pero ahora es el momento de mirar hacia adelante.<\/p>\n<p>(ers\/rml)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exjuez brasile\u00f1o Sergio Moro habla con DW sobre su reaproximaci\u00f3n al bolsonarismo y dice que las protestas deben servir de alerta para el pr\u00f3ximo Gobierno de Lula.Exjuez federal, exministro,&hellip; <\/p>\n","protected":false},"author":505,"featured_media":35127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-35153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-america-latina"],"_links":{"self":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts\/35153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/users\/505"}],"replies":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/comments?post=35153"}],"version-history":[{"count":0,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/posts\/35153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/media\/35127"}],"wp:attachment":[{"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/media?parent=35153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/categories?post=35153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veneportal.com\/noticias\/wp-json\/wp\/v2\/tags?post=35153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}