{"id":6625,"date":"2021-10-11T15:05:13","date_gmt":"2021-10-11T19:05:13","guid":{"rendered":"https:\/\/veneportal.com\/clasificados\/listing\/inteligencia-emocional-para-el-liderazgo-efectivo-y-colaboracion\/"},"modified":"2021-10-11T15:05:23","modified_gmt":"2021-10-11T19:05:23","slug":"inteligencia-emocional-para-el-liderazgo-efectivo-y-colaboracion","status":"publish","type":"rtcl_listing","link":"https:\/\/veneportal.com\/clasificados\/listing\/inteligencia-emocional-para-el-liderazgo-efectivo-y-colaboracion\/","title":{"rendered":"Inteligencia emocional para el liderazgo efectivo y colaboraci\u00f3n"},"content":{"rendered":"<div class=\"preview-expand-header d-flex position-relative\">\n<h1 class=\"nav-target pt-3 mt-3 pt-sm-4 mt-sm-3\">Sobre este curso<\/h1>\n<p><a class=\"show-on-focus\" href=\"https:\/\/www.edx.org\/es\/course\/inteligencia-emocional-para-el-liderazgo-efectiv-2?index=spanish_product&amp;queryID=a5e55c460a7dc6e400cf25bc3c717cdc&amp;position=14#about-this-course\" target=\"_blank\" rel=\"noopener\">Omitir Sobre este curso<\/a><\/div>\n<div class=\"preview-expand-body m-0 expanded\">\n<div class=\"mt-2 lead-sm html-data\">\n<p>El liderazgo emocional para la construcci\u00f3n de un efectivo equipo de trabajo es un conjunto de habilidades profesionales y personales, as\u00ed como cualidades y actitudes que permiten desempe\u00f1ar un rol orientado a resultados positivos para mejorar la calidad de vida personal y laboral; que favorece el cumplimiento de las metas y objetivos quecada persona define.<\/p>\n<p>Este curso online aporta una visi\u00f3n pr\u00e1ctica del liderazgo emocional efectivo. Durante las diversas actividades, analizar\u00e1s, evaluar\u00e1s y conocer\u00e1s herramientas pr\u00e1cticas, para poder definir y construir un equipo de trabajo de alto rendimiento y autodirigido en un ambiente social o profesional.<\/p>\n<p>En este curso de inteligencia emocional tambi\u00e9n aprender\u00e1s c\u00f3mo manejar la construcci\u00f3n emocional en los diferentes tipos de liderazgo que se presentan en nuestra vida profesional y cotidiana.<\/p>\n<\/div>\n<\/div>\n","protected":false},"author":490,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-6625","rtcl_listing","type-rtcl_listing","status-publish","hentry","rtcl_category-cosas-gratis","listing-item","rtcl-listing-item"],"_links":{"self":[{"href":"https:\/\/veneportal.com\/clasificados\/wp-json\/wp\/v2\/rtcl_listing\/6625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veneportal.com\/clasificados\/wp-json\/wp\/v2\/rtcl_listing"}],"about":[{"href":"https:\/\/veneportal.com\/clasificados\/wp-json\/wp\/v2\/types\/rtcl_listing"}],"author":[{"embeddable":true,"href":"https:\/\/veneportal.com\/clasificados\/wp-json\/wp\/v2\/users\/490"}],"replies":[{"embeddable":true,"href":"https:\/\/veneportal.com\/clasificados\/wp-json\/wp\/v2\/comments?post=6625"}],"wp:attachment":[{"href":"https:\/\/veneportal.com\/clasificados\/wp-json\/wp\/v2\/media?parent=6625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}